{"id":41,"count":10,"description":"","link":"https:\/\/hotel-cdg.com\/en\/category\/tips-tricks\/","name":"Tips &amp; Tricks","slug":"tips-tricks","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives of Tips &amp; Tricks - CDG Hotel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hotel-cdg.com\/en\/category\/tips-tricks\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives of Tips &amp; Tricks - CDG Hotel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hotel-cdg.com\/en\/category\/tips-tricks\/\" \/>\n<meta property=\"og:site_name\" content=\"CDG Hotel\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hotel-cdg.com\/wp-content\/uploads\/2024\/06\/airport-335589_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1275\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/hotel-cdg.com\\\/en\\\/category\\\/tips-tricks\\\/\",\"url\":\"https:\\\/\\\/hotel-cdg.com\\\/en\\\/category\\\/tips-tricks\\\/\",\"name\":\"Archives of Tips &amp; Tricks - CDG Hotel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hotel-cdg.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hotel-cdg.com\\\/en\\\/category\\\/tips-tricks\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hotel-cdg.com\\\/en\\\/category\\\/tips-tricks\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hotel-cdg.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tips &amp; Tricks\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hotel-cdg.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/hotel-cdg.com\\\/en\\\/\",\"name\":\"H\u00f4tel CDG\",\"description\":\"Find a hotel at Roissy CDG airport\",\"publisher\":{\"@id\":\"https:\\\/\\\/hotel-cdg.com\\\/en\\\/#organization\"},\"alternateName\":\"H\u00f4tel \u00e0 Roissy CDG\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hotel-cdg.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hotel-cdg.com\\\/en\\\/#organization\",\"name\":\"GDG Hotel\",\"alternateName\":\"Hotel at Roissy CDG\",\"url\":\"https:\\\/\\\/hotel-cdg.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/hotel-cdg.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hotel-cdg.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/refined_logo_paris_airport_info.jpg\",\"contentUrl\":\"https:\\\/\\\/hotel-cdg.com\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/refined_logo_paris_airport_info.jpg\",\"width\":1024,\"height\":1024,\"caption\":\"GDG Hotel\"},\"image\":{\"@id\":\"https:\\\/\\\/hotel-cdg.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives of Tips &amp; Tricks - CDG Hotel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hotel-cdg.com\/en\/category\/tips-tricks\/","og_locale":"en_US","og_type":"article","og_title":"Archives of Tips &amp; Tricks - CDG Hotel","og_url":"https:\/\/hotel-cdg.com\/en\/category\/tips-tricks\/","og_site_name":"CDG Hotel","og_image":[{"width":1920,"height":1275,"url":"https:\/\/hotel-cdg.com\/wp-content\/uploads\/2024\/06\/airport-335589_1920.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hotel-cdg.com\/en\/category\/tips-tricks\/","url":"https:\/\/hotel-cdg.com\/en\/category\/tips-tricks\/","name":"Archives of Tips &amp; Tricks - CDG Hotel","isPartOf":{"@id":"https:\/\/hotel-cdg.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/hotel-cdg.com\/en\/category\/tips-tricks\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/hotel-cdg.com\/en\/category\/tips-tricks\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hotel-cdg.com\/en\/"},{"@type":"ListItem","position":2,"name":"Tips &amp; Tricks"}]},{"@type":"WebSite","@id":"https:\/\/hotel-cdg.com\/en\/#website","url":"https:\/\/hotel-cdg.com\/en\/","name":"H\u00f4tel CDG","description":"Find a hotel at Roissy CDG airport","publisher":{"@id":"https:\/\/hotel-cdg.com\/en\/#organization"},"alternateName":"H\u00f4tel \u00e0 Roissy CDG","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hotel-cdg.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hotel-cdg.com\/en\/#organization","name":"GDG Hotel","alternateName":"Hotel at Roissy CDG","url":"https:\/\/hotel-cdg.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hotel-cdg.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/hotel-cdg.com\/wp-content\/uploads\/2024\/06\/refined_logo_paris_airport_info.jpg","contentUrl":"https:\/\/hotel-cdg.com\/wp-content\/uploads\/2024\/06\/refined_logo_paris_airport_info.jpg","width":1024,"height":1024,"caption":"GDG Hotel"},"image":{"@id":"https:\/\/hotel-cdg.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hotel-cdg.com\/en\/wp-json\/wp\/v2\/categories\/41","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hotel-cdg.com\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/hotel-cdg.com\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/hotel-cdg.com\/en\/wp-json\/wp\/v2\/posts?categories=41"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}